{"id":16793,"date":"2025-11-14T16:26:41","date_gmt":"2025-11-14T15:26:41","guid":{"rendered":"https:\/\/www.gruporecoletas.com\/noticias\/?p=16793"},"modified":"2025-11-18T16:53:11","modified_gmt":"2025-11-18T15:53:11","slug":"el-hospital-recoletas-salud-burgos-colabora-con-la-asociacion-de-diabetes-de-burgos-para-realizar-pruebas-de-glucosa-en-sangre","status":"publish","type":"post","link":"https:\/\/www.gruporecoletas.com\/noticias\/el-hospital-recoletas-salud-burgos-colabora-con-la-asociacion-de-diabetes-de-burgos-para-realizar-pruebas-de-glucosa-en-sangre\/","title":{"rendered":"El Hospital Recoletas Salud Burgos colabora con la Asociaci\u00f3n de Diabetes de Burgos para realizar pruebas de glucosa en sangre"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><strong><em>M\u00e1s de un centenar de personas se pudieron hacer ayer la medici\u00f3n dentro de las instalaciones hospitalarias<\/em><\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Son numerosas las actividades que est\u00e1n llev\u00e1ndose a cabo durante esta semana y la pr\u00f3xima con motivo de la celebraci\u00f3n del D\u00eda Mundial de la Diabetes. Y, este a\u00f1o, el Hospital Recoletas Salud, en colaboraci\u00f3n con la Asociaci\u00f3n de Diabetes de Burgos ha realizado a m\u00e1s de un centenar de pacientes pruebas gratuitas de medici\u00f3n de glucosa en sangre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una iniciativa que forma parte de la campa\u00f1a de concienciaci\u00f3n a la poblaci\u00f3n burgalesa sobre diabetes y la importancia de un diagn\u00f3stico a tiempo y un estilo de vida y alimentaci\u00f3n saludable.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El presidente de la Asociaci\u00f3n Diabetes Burgos, Mariano Cerd\u00e1n acompa\u00f1ado de voluntarios se ha acercado hasta el hospital Recoletas Salud donde todos ellos, han ofrecido informaci\u00f3n acerca de la Asociaci\u00f3n y de las actividades que realizan a muchas de las personas que se han interesado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde el servicio de Endocrinolog\u00eda del hospital Recoletas Salud insisten en la prevenci\u00f3n, en adquirir h\u00e1bitos de vida saludable y destacan la importancia de un diagn\u00f3stico precoz para realizar cuanto antes el abordaje terap\u00e9utico adecuado y as\u00ed evitar la evoluci\u00f3n de la diabetes y sus complicaciones. Asimismo, recuerdan que el 80% de las personas que sufren diabetes tipo 2 podr\u00edan haberla evitado con una alimentaci\u00f3n saludable, actividad f\u00edsica regular, un peso adecuado y evitando el tabaco. Pilar G\u00f3mez, directora gerente de Recoletas Salud Burgos, ha agradecido al equipo de enfermer\u00eda su colaboraci\u00f3n y ha reiterado su apoyo a la Asociaci\u00f3n de Diabetes Burgos, se\u00f1alado que \u201ccolaborar en el control adecuado de la diabetes es esencial para prevenir complicaciones m\u00e1s graves que puedan surgir<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Son numerosas las actividades que est\u00e1n llev\u00e1ndose a cabo durante esta semana y la pr\u00f3xima con motivo de la celebraci\u00f3n del D\u00eda Mundial de la Diabetes. Y, este a\u00f1o, el Hospital Recoletas Salud, en colaboraci\u00f3n con la Asociaci\u00f3n de Diabetes de Burgos ha realizado a m\u00e1s de un centenar de pacientes pruebas gratuitas de medici\u00f3n [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-16793","post","type-post","status-publish","format-standard","hentry","category-grupo-recoletas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>El Hospital Recoletas Salud Burgos colabora con la Asociaci\u00f3n de Diabetes de Burgos para realizar pruebas de glucosa en sangre - Noticias Grupo Recoletas<\/title>\n<meta name=\"description\" content=\"Descubre la importancia de la detecci\u00f3n temprana de la diabetes y c\u00f3mo un estilo de vida saludable puede marcar la diferencia.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.gruporecoletas.com\/noticias\/el-hospital-recoletas-salud-burgos-colabora-con-la-asociacion-de-diabetes-de-burgos-para-realizar-pruebas-de-glucosa-en-sangre\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Hospital Recoletas Salud Burgos colabora con la Asociaci\u00f3n de Diabetes de Burgos para realizar pruebas de glucosa en sangre\" \/>\n<meta property=\"og:description\" content=\"Descubre la importancia de la detecci\u00f3n temprana de la diabetes y c\u00f3mo un estilo de vida saludable puede marcar la diferencia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.gruporecoletas.com\/noticias\/el-hospital-recoletas-salud-burgos-colabora-con-la-asociacion-de-diabetes-de-burgos-para-realizar-pruebas-de-glucosa-en-sangre\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias Grupo Recoletas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/GrupoRecoletas\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-14T15:26:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-18T15:53:11+00:00\" \/>\n<meta name=\"author\" content=\"Recoletas Red Hospitalaria\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@GrupoRecoletas\" \/>\n<meta name=\"twitter:site\" content=\"@GrupoRecoletas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Recoletas Red Hospitalaria\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.gruporecoletas.com\\\/noticias\\\/el-hospital-recoletas-salud-burgos-colabora-con-la-asociacion-de-diabetes-de-burgos-para-realizar-pruebas-de-glucosa-en-sangre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.gruporecoletas.com\\\/noticias\\\/el-hospital-recoletas-salud-burgos-colabora-con-la-asociacion-de-diabetes-de-burgos-para-realizar-pruebas-de-glucosa-en-sangre\\\/\"},\"author\":{\"name\":\"Recoletas Red Hospitalaria\",\"@id\":\"https:\\\/\\\/www.gruporecoletas.com\\\/noticias\\\/#\\\/schema\\\/person\\\/3c6ac429828d1f5e3d3bd99f4da9b02c\"},\"headline\":\"El Hospital Recoletas Salud Burgos colabora con la Asociaci\u00f3n de Diabetes de Burgos para realizar pruebas de glucosa en sangre\",\"datePublished\":\"2025-11-14T15:26:41+00:00\",\"dateModified\":\"2025-11-18T15:53:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.gruporecoletas.com\\\/noticias\\\/el-hospital-recoletas-salud-burgos-colabora-con-la-asociacion-de-diabetes-de-burgos-para-realizar-pruebas-de-glucosa-en-sangre\\\/\"},\"wordCount\":332,\"articleSection\":[\"Grupo Recoletas\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.gruporecoletas.com\\\/noticias\\\/el-hospital-recoletas-salud-burgos-colabora-con-la-asociacion-de-diabetes-de-burgos-para-realizar-pruebas-de-glucosa-en-sangre\\\/\",\"url\":\"https:\\\/\\\/www.gruporecoletas.com\\\/noticias\\\/el-hospital-recoletas-salud-burgos-colabora-con-la-asociacion-de-diabetes-de-burgos-para-realizar-pruebas-de-glucosa-en-sangre\\\/\",\"name\":\"El Hospital Recoletas Salud Burgos colabora con la Asociaci\u00f3n de Diabetes de Burgos para realizar pruebas de glucosa en sangre - Noticias Grupo Recoletas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.gruporecoletas.com\\\/noticias\\\/#website\"},\"datePublished\":\"2025-11-14T15:26:41+00:00\",\"dateModified\":\"2025-11-18T15:53:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.gruporecoletas.com\\\/noticias\\\/#\\\/schema\\\/person\\\/3c6ac429828d1f5e3d3bd99f4da9b02c\"},\"description\":\"Descubre la importancia de la detecci\u00f3n temprana de la diabetes y c\u00f3mo un estilo de vida saludable puede marcar la diferencia.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.gruporecoletas.com\\\/noticias\\\/el-hospital-recoletas-salud-burgos-colabora-con-la-asociacion-de-diabetes-de-burgos-para-realizar-pruebas-de-glucosa-en-sangre\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.gruporecoletas.com\\\/noticias\\\/el-hospital-recoletas-salud-burgos-colabora-con-la-asociacion-de-diabetes-de-burgos-para-realizar-pruebas-de-glucosa-en-sangre\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.gruporecoletas.com\\\/noticias\\\/el-hospital-recoletas-salud-burgos-colabora-con-la-asociacion-de-diabetes-de-burgos-para-realizar-pruebas-de-glucosa-en-sangre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.gruporecoletas.com\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Hospital Recoletas Salud Burgos colabora con la Asociaci\u00f3n de Diabetes de Burgos para realizar pruebas de glucosa en sangre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.gruporecoletas.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.gruporecoletas.com\\\/noticias\\\/\",\"name\":\"Noticias Grupo Recoletas\",\"description\":\"Grupo Recoletas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.gruporecoletas.com\\\/noticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.gruporecoletas.com\\\/noticias\\\/#\\\/schema\\\/person\\\/3c6ac429828d1f5e3d3bd99f4da9b02c\",\"name\":\"Recoletas Red Hospitalaria\",\"url\":\"https:\\\/\\\/www.gruporecoletas.com\\\/noticias\\\/author\\\/comunicacion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"El Hospital Recoletas Salud Burgos colabora con la Asociaci\u00f3n de Diabetes de Burgos para realizar pruebas de glucosa en sangre - Noticias Grupo Recoletas","description":"Descubre la importancia de la detecci\u00f3n temprana de la diabetes y c\u00f3mo un estilo de vida saludable puede marcar la diferencia.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.gruporecoletas.com\/noticias\/el-hospital-recoletas-salud-burgos-colabora-con-la-asociacion-de-diabetes-de-burgos-para-realizar-pruebas-de-glucosa-en-sangre\/","og_locale":"es_ES","og_type":"article","og_title":"El Hospital Recoletas Salud Burgos colabora con la Asociaci\u00f3n de Diabetes de Burgos para realizar pruebas de glucosa en sangre","og_description":"Descubre la importancia de la detecci\u00f3n temprana de la diabetes y c\u00f3mo un estilo de vida saludable puede marcar la diferencia.","og_url":"https:\/\/www.gruporecoletas.com\/noticias\/el-hospital-recoletas-salud-burgos-colabora-con-la-asociacion-de-diabetes-de-burgos-para-realizar-pruebas-de-glucosa-en-sangre\/","og_site_name":"Noticias Grupo Recoletas","article_publisher":"https:\/\/www.facebook.com\/GrupoRecoletas\/","article_published_time":"2025-11-14T15:26:41+00:00","article_modified_time":"2025-11-18T15:53:11+00:00","author":"Recoletas Red Hospitalaria","twitter_card":"summary_large_image","twitter_creator":"@GrupoRecoletas","twitter_site":"@GrupoRecoletas","twitter_misc":{"Escrito por":"Recoletas Red Hospitalaria","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.gruporecoletas.com\/noticias\/el-hospital-recoletas-salud-burgos-colabora-con-la-asociacion-de-diabetes-de-burgos-para-realizar-pruebas-de-glucosa-en-sangre\/#article","isPartOf":{"@id":"https:\/\/www.gruporecoletas.com\/noticias\/el-hospital-recoletas-salud-burgos-colabora-con-la-asociacion-de-diabetes-de-burgos-para-realizar-pruebas-de-glucosa-en-sangre\/"},"author":{"name":"Recoletas Red Hospitalaria","@id":"https:\/\/www.gruporecoletas.com\/noticias\/#\/schema\/person\/3c6ac429828d1f5e3d3bd99f4da9b02c"},"headline":"El Hospital Recoletas Salud Burgos colabora con la Asociaci\u00f3n de Diabetes de Burgos para realizar pruebas de glucosa en sangre","datePublished":"2025-11-14T15:26:41+00:00","dateModified":"2025-11-18T15:53:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.gruporecoletas.com\/noticias\/el-hospital-recoletas-salud-burgos-colabora-con-la-asociacion-de-diabetes-de-burgos-para-realizar-pruebas-de-glucosa-en-sangre\/"},"wordCount":332,"articleSection":["Grupo Recoletas"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.gruporecoletas.com\/noticias\/el-hospital-recoletas-salud-burgos-colabora-con-la-asociacion-de-diabetes-de-burgos-para-realizar-pruebas-de-glucosa-en-sangre\/","url":"https:\/\/www.gruporecoletas.com\/noticias\/el-hospital-recoletas-salud-burgos-colabora-con-la-asociacion-de-diabetes-de-burgos-para-realizar-pruebas-de-glucosa-en-sangre\/","name":"El Hospital Recoletas Salud Burgos colabora con la Asociaci\u00f3n de Diabetes de Burgos para realizar pruebas de glucosa en sangre - Noticias Grupo Recoletas","isPartOf":{"@id":"https:\/\/www.gruporecoletas.com\/noticias\/#website"},"datePublished":"2025-11-14T15:26:41+00:00","dateModified":"2025-11-18T15:53:11+00:00","author":{"@id":"https:\/\/www.gruporecoletas.com\/noticias\/#\/schema\/person\/3c6ac429828d1f5e3d3bd99f4da9b02c"},"description":"Descubre la importancia de la detecci\u00f3n temprana de la diabetes y c\u00f3mo un estilo de vida saludable puede marcar la diferencia.","breadcrumb":{"@id":"https:\/\/www.gruporecoletas.com\/noticias\/el-hospital-recoletas-salud-burgos-colabora-con-la-asociacion-de-diabetes-de-burgos-para-realizar-pruebas-de-glucosa-en-sangre\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.gruporecoletas.com\/noticias\/el-hospital-recoletas-salud-burgos-colabora-con-la-asociacion-de-diabetes-de-burgos-para-realizar-pruebas-de-glucosa-en-sangre\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.gruporecoletas.com\/noticias\/el-hospital-recoletas-salud-burgos-colabora-con-la-asociacion-de-diabetes-de-burgos-para-realizar-pruebas-de-glucosa-en-sangre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.gruporecoletas.com\/noticias\/"},{"@type":"ListItem","position":2,"name":"El Hospital Recoletas Salud Burgos colabora con la Asociaci\u00f3n de Diabetes de Burgos para realizar pruebas de glucosa en sangre"}]},{"@type":"WebSite","@id":"https:\/\/www.gruporecoletas.com\/noticias\/#website","url":"https:\/\/www.gruporecoletas.com\/noticias\/","name":"Noticias Grupo Recoletas","description":"Grupo Recoletas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.gruporecoletas.com\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.gruporecoletas.com\/noticias\/#\/schema\/person\/3c6ac429828d1f5e3d3bd99f4da9b02c","name":"Recoletas Red Hospitalaria","url":"https:\/\/www.gruporecoletas.com\/noticias\/author\/comunicacion\/"}]}},"_links":{"self":[{"href":"https:\/\/www.gruporecoletas.com\/noticias\/wp-json\/wp\/v2\/posts\/16793","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gruporecoletas.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gruporecoletas.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gruporecoletas.com\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gruporecoletas.com\/noticias\/wp-json\/wp\/v2\/comments?post=16793"}],"version-history":[{"count":1,"href":"https:\/\/www.gruporecoletas.com\/noticias\/wp-json\/wp\/v2\/posts\/16793\/revisions"}],"predecessor-version":[{"id":16794,"href":"https:\/\/www.gruporecoletas.com\/noticias\/wp-json\/wp\/v2\/posts\/16793\/revisions\/16794"}],"wp:attachment":[{"href":"https:\/\/www.gruporecoletas.com\/noticias\/wp-json\/wp\/v2\/media?parent=16793"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gruporecoletas.com\/noticias\/wp-json\/wp\/v2\/categories?post=16793"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gruporecoletas.com\/noticias\/wp-json\/wp\/v2\/tags?post=16793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}